{"id":2498,"date":"2023-01-26T12:17:17","date_gmt":"2023-01-26T11:17:17","guid":{"rendered":"https:\/\/compare-energie.fr\/blog\/?p=2498"},"modified":"2023-01-26T12:32:23","modified_gmt":"2023-01-26T11:32:23","slug":"augmentation-des-trv-de-gaz-et-delectricite-en-ce-debut-dannee-2023","status":"publish","type":"post","link":"https:\/\/compare-energie.fr\/blog\/augmentation-des-trv-de-gaz-et-delectricite-en-ce-debut-dannee-2023\/","title":{"rendered":"Augmentation des TRV de gaz et d\u2019\u00e9lectricit\u00e9 en ce d\u00e9but d\u2019ann\u00e9e 2023"},"content":{"rendered":"<p><strong>Mauvaise nouvelle pour votre portefeuille\u00a0: les tarifs de vente r\u00e9glement\u00e9s de l\u2019\u00e9nergie augmentent en moyenne de +15\u00a0%. C\u2019est d\u00e9j\u00e0 chose faite pour le gaz depuis le 1er janvier 2023. L\u2019\u00e9lectricit\u00e9 devrait suivre le 1er f\u00e9vrier. Cette hausse de prix est toutefois limit\u00e9e gr\u00e2ce \u00e0 l\u2019application du bouclier tarifaire.<\/strong><\/p>\n<h3>TRV de gaz : +15 % le 1er janvier 2023<\/h3>\n<p>Mis en place suite \u00e0 la <a href=\"https:\/\/compare-energie.fr\/blog\/hausse-sans-precedent-des-prix-du-gaz-naturel-le-1er-octobre-2021\/\">hausse sans pr\u00e9c\u00e9dent des tarifs r\u00e9glement\u00e9s de vente de gaz naturel le 1er octobre 2021<\/a>, le <a href=\"https:\/\/compare-energie.fr\/blog\/quest-ce-que-le-bouclier-tarifaire-contre-la-hausse-des-prix-de-lenergie\/\">bouclier tarifaire<\/a> devait en principe prendre fin le 31 d\u00e9cembre 2022. Dans la loi de finances pour 2023, le gouvernement a toutefois d\u00e9cid\u00e9 une nouvelle fois de prolonger ce bouclier tarifaire jusqu\u2019au 30 juin 2023. Cette loi stipule \u00e9galement une majoration de +15 % TTC des TRV de gaz \u00e0 partir du 1er janvier 2023. Les Fran\u00e7ais avaient b\u00e9n\u00e9fici\u00e9 d\u2019un gel du prix du gaz entre le 1er novembre 2021 et le 31 d\u00e9cembre 2022. Mais d\u00e8s ce mois de janvier, ils verront leur facture de gaz augmenter de +15 % s\u2019ils ont un contrat au tarif r\u00e9glement\u00e9 (chez Engie ou aupr\u00e8s d\u2019une <a href=\"https:\/\/compare-energie.fr\/blog\/que-sont-les-entreprises-locales-de-distribution\/\">entreprise locale de distribution<\/a>) ou un contrat dont les prix sont index\u00e9s sur les TRV. Seuls les particuliers ayant encore un contrat \u00e0 prix fixe seront \u00e9pargn\u00e9s. Cette hausse n\u2019est toutefois rien au regard de la hausse r\u00e9elle des prix du gaz sur le march\u00e9.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-2501 size-full\" src=\"https:\/\/compare-energie.fr\/blog\/wp-content\/uploads\/2023\/01\/Augmentation-des-TRV-de-gaz-et-d\u2019e\u0301lectricite\u0301-en-ce-de\u0301but-d\u2019anne\u0301e-2023-chart.png\" alt=\"\" width=\"651\" height=\"363\" srcset=\"https:\/\/compare-energie.fr\/blog\/wp-content\/uploads\/2023\/01\/Augmentation-des-TRV-de-gaz-et-d\u2019e\u0301lectricite\u0301-en-ce-de\u0301but-d\u2019anne\u0301e-2023-chart.png 651w, https:\/\/compare-energie.fr\/blog\/wp-content\/uploads\/2023\/01\/Augmentation-des-TRV-de-gaz-et-d\u2019e\u0301lectricite\u0301-en-ce-de\u0301but-d\u2019anne\u0301e-2023-chart-300x167.png 300w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/p>\n<p><em>Comparaison de l\u2019\u00e9volution des tarifs r\u00e9glement\u00e9s moyens de vente de gaz d\u2019Engie avec gel et sans gel \u2013 Source : CRE, 6 janvier 2023<\/em><\/p>\n<h3>Disparition des TRV de gaz cet \u00e9t\u00e9<\/h3>\n<p>Pour rappel, <a href=\"https:\/\/compare-energie.fr\/blog\/fin-des-tarifs-reglementes-du-gaz-naturel\/\">les tarifs r\u00e9glement\u00e9s de vente de gaz naturel dispara\u00eetront le 1er juillet 2023<\/a>. Ces tarifs ne sont plus commercialis\u00e9s depuis fin 2019 et ils ont d\u00e9j\u00e0 \u00e9t\u00e9 supprim\u00e9s fin 2020 pour les clients professionnels. Cet \u00e9t\u00e9, ce sera au tour des clients r\u00e9sidentiels. Si vous \u00eates encore client des TRVg, vous n\u2019aurez d\u2019autre choix que de basculer sur une offre de march\u00e9. Nous vous recommandons de <a href=\"https:\/\/compare-energie.fr\/comparateur-fournisseurs\/gaz\/\">comparer les diff\u00e9rentes offres disponibles<\/a> avant la date fatidique. Sinon, vous basculerez automatiquement sur une offre de march\u00e9 de votre fournisseur actuel, qui n\u2019est pas toujours la plus int\u00e9ressante.<\/p>\n<h3>TRV d\u2019\u00e9lectricit\u00e9 : hausse attendue de +15 % le 1er f\u00e9vrier 2023<\/h3>\n<p>Une hausse des tarifs r\u00e9glement\u00e9s de vente d\u2019\u00e9lectricit\u00e9 est attendue pour le 1er f\u00e9vrier 2023. Une fois encore, le gouvernement a heureusement pr\u00e9vu de limiter \u00e0 +15 % TTC la hausse des TRVe et de ne pas suivre les recommandations de la CRE (Commission de r\u00e9gulation de l\u2019\u00e9nergie). Bas\u00e9s sur les prix de gros r\u00e9els du march\u00e9, la proposition de la CRE pour le tarif bleu r\u00e9sidentiel \u00e9tait en effet de +99,36 % par rapport aux TRV qui avaient \u00e9t\u00e9 gel\u00e9s le 1er f\u00e9vrier 2022. Comme pour le gaz naturel, c\u2019est l\u2019\u00c9tat qui compensera la diff\u00e9rence aupr\u00e8s des fournisseurs.<\/p>\n<p><a href=\"https:\/\/compare-energie.fr\/comparateur-fournisseurs\/\">Vous songez \u00e0 changer de fournisseur d\u2019\u00e9lectricit\u00e9 ? Comparez les tarifs avec un comparateur ind\u00e9pendant !<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mauvaise nouvelle pour votre portefeuille\u00a0: les tarifs de vente r\u00e9glement\u00e9s de l\u2019\u00e9nergie augmentent en moyenne de +15\u00a0%. C\u2019est d\u00e9j\u00e0 chose faite pour le gaz depuis le 1er janvier 2023. L\u2019\u00e9lectricit\u00e9 devrait suivre le 1er f\u00e9vrier. Cette hausse de prix est toutefois limit\u00e9e gr\u00e2ce \u00e0 l\u2019application du bouclier tarifaire. TRV de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1221,42],"yst_prominent_words":[619,315,1424,480,1422,1426,1423,1205,139,89,1425,523,362,539,726,113,535,541,542,985],"_links":{"self":[{"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/posts\/2498"}],"collection":[{"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":5,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/posts\/2498\/revisions"}],"predecessor-version":[{"id":2504,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/posts\/2498\/revisions\/2504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/media\/2505"}],"wp:attachment":[{"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/categories?post=2498"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/compare-energie.fr\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}